{"id":24549,"date":"2015-03-01T23:07:52","date_gmt":"2015-03-02T04:07:52","guid":{"rendered":"http:\/\/www.freeautomechanic.com\/mechanic\/forum\/?p=24549"},"modified":"2015-03-01T23:07:52","modified_gmt":"2015-03-02T04:07:52","slug":"2002-pontiac-montana","status":"publish","type":"post","link":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana","title":{"rendered":"2002 pontiac montana"},"content":{"rendered":"<p>3.4 died let it sit then it started now it is not starting just turning over and has backfired twice<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3.4 died let it sit then it started now it is not starting just turning over and has backfired twice<\/p>\n","protected":false},"author":10793,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[31],"tags":[9984,9954],"class_list":["post-24549","post","type-post","status-publish","format-standard","hentry","category-pontiac","tag-3-4-gm-no-start","tag-montana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2002 pontiac montana  - FreeAutoMechanic Advice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2002 pontiac montana\" \/>\n<meta property=\"og:description\" content=\"3.4 died let it sit then it started now it is not starting just turning over and has backfired twice\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana\" \/>\n<meta property=\"og:site_name\" content=\"FreeAutoMechanic Advice\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/freeautomechanic\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T04:07:52+00:00\" \/>\n<meta name=\"author\" content=\"Dakota Dillon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dakota Dillon\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2002 pontiac montana  - FreeAutoMechanic Advice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana","og_locale":"en_US","og_type":"article","og_title":"2002 pontiac montana","og_description":"3.4 died let it sit then it started now it is not starting just turning over and has backfired twice","og_url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana","og_site_name":"FreeAutoMechanic Advice","article_publisher":"https:\/\/www.facebook.com\/freeautomechanic","article_published_time":"2015-03-02T04:07:52+00:00","author":"Dakota Dillon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dakota Dillon"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana#article","isPartOf":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana"},"author":{"name":"Dakota Dillon","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/person\/40c991116a655a53f88c69de38b6d400"},"headline":"2002 pontiac montana","datePublished":"2015-03-02T04:07:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana"},"wordCount":21,"commentCount":1,"publisher":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#organization"},"keywords":["3.4 gm no start","Montana"],"articleSection":["Pontiac"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana","name":"2002 pontiac montana - FreeAutoMechanic Advice","isPartOf":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#website"},"datePublished":"2015-03-02T04:07:52+00:00","breadcrumb":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/2015\/03\/2002-pontiac-montana#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/"},{"@type":"ListItem","position":2,"name":"2002 pontiac montana"}]},{"@type":"WebSite","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#website","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/","name":"FreeAutoMechanic Advice","description":"Ask a Car Mechanic Questions for Free","publisher":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#organization","name":"FreeAutoMechanic Advice","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/logo\/image\/","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/uploads\/2020\/06\/cropped-auto_repair_questions.jpg","contentUrl":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/uploads\/2020\/06\/cropped-auto_repair_questions.jpg","width":250,"height":81,"caption":"FreeAutoMechanic Advice"},"image":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freeautomechanic","https:\/\/www.youtube.com\/freeautomechanic"]},{"@type":"Person","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/person\/40c991116a655a53f88c69de38b6d400","name":"Dakota Dillon","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/bd1d7878ed8988ef2667c65a7ed54337.jpg","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/bd1d7878ed8988ef2667c65a7ed54337.jpg","contentUrl":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/bd1d7878ed8988ef2667c65a7ed54337.jpg","caption":"Dakota Dillon"},"sameAs":["https:\/\/www.facebook.com\/tatercountry65"],"url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/dakota-dillon"}]}},"_links":{"self":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/posts\/24549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/users\/10793"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/comments?post=24549"}],"version-history":[{"count":0,"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/posts\/24549\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/media?parent=24549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/categories?post=24549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/tags?post=24549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}