{"id":15674,"name":"Jeremy324","url":"","description":"","link":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324","slug":"jeremy324","avatar_urls":{"24":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/17859f60d11fceddf17ec8fee0aec81d.jpg","48":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/86a50b53b75d7bc391ba668ccfb1e00d.jpg","96":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/5efd6982d482571c37b0923a1c84ecaa.jpg?ver=1778323424"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jeremy324, Author at FreeAutoMechanic Advice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Jeremy324\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324\" \/>\n<meta property=\"og:site_name\" content=\"FreeAutoMechanic Advice\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/85875bd375568b707d1721be278488f2?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jeremy324, Author at FreeAutoMechanic Advice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324","og_locale":"en_US","og_type":"profile","og_title":"Jeremy324","og_url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324","og_site_name":"FreeAutoMechanic Advice","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/85875bd375568b707d1721be278488f2?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324","name":"Jeremy324, Author at FreeAutoMechanic Advice","isPartOf":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#website"},"breadcrumb":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/"},{"@type":"ListItem","position":2,"name":"Archives for Jeremy324"}]},{"@type":"WebSite","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#website","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/","name":"FreeAutoMechanic Advice","description":"Ask a Car Mechanic Questions for Free","publisher":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#organization","name":"FreeAutoMechanic Advice","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/logo\/image\/","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/uploads\/2020\/06\/cropped-auto_repair_questions.jpg","contentUrl":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/uploads\/2020\/06\/cropped-auto_repair_questions.jpg","width":250,"height":81,"caption":"FreeAutoMechanic Advice"},"image":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freeautomechanic","https:\/\/www.youtube.com\/freeautomechanic"]},{"@type":"Person","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/#\/schema\/person\/57fe18da90469167b7033e7be4f09362","name":"Jeremy324","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/5efd6982d482571c37b0923a1c84ecaa.jpg?ver=1778323424","url":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/5efd6982d482571c37b0923a1c84ecaa.jpg?ver=1778323424","contentUrl":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-content\/litespeed\/avatar\/5efd6982d482571c37b0923a1c84ecaa.jpg?ver=1778323424","caption":"Jeremy324"},"mainEntityOfPage":{"@id":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/author\/jeremy324"}}]}},"_links":{"self":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/users\/15674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freeautomechanic.com\/mechanic\/forum\/wp-json\/wp\/v2\/users"}]}}